{"id":1856,"name":"Maison Les Galettes","url":"","description":"","link":"https:\/\/maisonlesgalettes.com\/en\/author\/galettes\/","slug":"galettes","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d286afd883e228be39df78b137af0e6751c0372ec7a72fd812e01d41cd2d62?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d286afd883e228be39df78b137af0e6751c0372ec7a72fd812e01d41cd2d62?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d286afd883e228be39df78b137af0e6751c0372ec7a72fd812e01d41cd2d62?s=96&d=mm&r=g"},"meta":[],"yoast_head":null,"yoast_head_json":null,"_links":{"self":[{"href":"https:\/\/maisonlesgalettes.com\/en\/wp-json\/wp\/v2\/users\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maisonlesgalettes.com\/en\/wp-json\/wp\/v2\/users"}]}}